{"id":8353,"date":"2025-09-17T15:58:57","date_gmt":"2025-09-17T21:58:57","guid":{"rendered":"https:\/\/radioguerrerosonline.com\/?p=8353"},"modified":"2025-09-17T15:58:58","modified_gmt":"2025-09-17T21:58:58","slug":"gobierno-del-edomex-invita-a-participar-en-el-segundo-simulacro-nacional-2025","status":"publish","type":"post","link":"https:\/\/radioguerrerosonline.com\/index.php\/2025\/09\/17\/gobierno-del-edomex-invita-a-participar-en-el-segundo-simulacro-nacional-2025\/","title":{"rendered":"Gobierno del EdoM\u00e9x invita a participar en el Segundo Simulacro Nacional 2025"},"content":{"rendered":"\n<p><strong>TOLUCA,\u00a0Estado de M\u00e9xico a 17 de Septiembre de 2025.<\/strong><\/p>\n\n\n\n<p>\u2022El Gobierno del Estado de M\u00e9xico, a trav\u00e9s de Protecci\u00f3n Civil\u00a0estatal, invita a las y los mexiquenses a participar en el Segundo Simulacro Nacional 2025 a realizarse el pr\u00f3ximo viernes 19 de septiembre a las 12:00 horas,\u00a0bajo la hip\u00f3tesis de un sismo de magnitud 8.1 con epicentro en L\u00e1zaro C\u00e1rdenas, Michoac\u00e1n.<\/p>\n\n\n\n<p>El alertamiento ser\u00e1 activado en los 10 mil altavoces del Centro de Control, Comando, Comunicaci\u00f3n, C\u00f3mputo y Calidad (C5) que est\u00e1n distribuidos en los diferentes municipios del Estado de M\u00e9xico y, por primera vez a nivel nacional, se enviar\u00e1 un mensaje de alerta a m\u00e1s de 80 millones de tel\u00e9fonos celulares.<\/p>\n\n\n\n<p>Esta alerta en los tel\u00e9fonos m\u00f3viles no requiere de internet, saldo o instalaci\u00f3n de aplicaciones, \u00fanicamente es necesario tener se\u00f1al y activar las alertas inal\u00e1mbricas.<\/p>\n\n\n\n<p>Para&nbsp;activarlas&nbsp;en Android, se debe acceder a Ajustes&gt;Notificaciones&gt;Ajustes avanzados&gt;Alertas de emergencia inal\u00e1mbricas. En iOs se podr\u00e1 activar en Configuraci\u00f3n&gt;Notificaciones&gt;Alertas Gubernamentales. En caso de dudas, llamar al 079 al Centro de Atenci\u00f3n Ciudadana del Gobierno de M\u00e9xico.<\/p>\n\n\n\n<p>En el Estado de M\u00e9xico, se instalar\u00e1 el Comit\u00e9 de Emergencias en el C5 y se activar\u00e1n los protocolos de supervisi\u00f3n y atenci\u00f3n en toda la entidad.<\/p>\n\n\n\n<p>Se realizar\u00e1 la evacuaci\u00f3n de inmuebles y la activaci\u00f3n de los protocolos de respuesta a emergencias por parte de las autoridades correspondientes en los municipios del Estado de M\u00e9xico; empresas del sector p\u00fablico, privado, social y acad\u00e9mico, por lo que se extiende la invitaci\u00f3n a la poblaci\u00f3n a registrar los inmuebles en la siguiente p\u00e1gina:&nbsp;<a href=\"https:\/\/simulacronacional.sspc.gob.mx\/segundosimulacronacional2025\/\">https:\/\/simulacronacional.sspc.gob.mx\/segundosimulacronacional2025\/<\/a>.<\/p>\n\n\n\n<p>El registro, ayudar\u00e1 a verificar y evaluar las rutas de evacuaci\u00f3n, puntos de seguridad y respuesta. Al t\u00e9rmino del ejercicio se podr\u00e1 obtener una constancia de participaci\u00f3n, emitida en la misma plataforma digital en donde se realiz\u00f3 el registro.<\/p>\n\n\n\n<p>A 40 a\u00f1os del sismo de 1985, el Gobierno del Estado de M\u00e9xico reafirma su compromiso con la cultura de la Protecci\u00f3n Civil y la gesti\u00f3n de riesgos para salvaguardar la integridad de las familias mexiquenses.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>TOLUCA,\u00a0Estado de M\u00e9xico a 17 de Septiembre de 2025. \u2022El Gobierno del Estado de M\u00e9xico, a trav\u00e9s de Protecci\u00f3n Civil\u00a0estatal, invita a las y los mexiquenses a participar en el Segundo Simulacro Nacional 2025 a realizarse el pr\u00f3ximo viernes 19 de septiembre a las 12:00 horas,\u00a0bajo la hip\u00f3tesis de un sismo de magnitud 8.1 con [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":8354,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[1],"tags":[49,59],"class_list":{"0":"post-8353","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-blog","8":"tag-edomex-2","9":"tag-nacional"},"_links":{"self":[{"href":"https:\/\/radioguerrerosonline.com\/index.php\/wp-json\/wp\/v2\/posts\/8353","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radioguerrerosonline.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radioguerrerosonline.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radioguerrerosonline.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radioguerrerosonline.com\/index.php\/wp-json\/wp\/v2\/comments?post=8353"}],"version-history":[{"count":1,"href":"https:\/\/radioguerrerosonline.com\/index.php\/wp-json\/wp\/v2\/posts\/8353\/revisions"}],"predecessor-version":[{"id":8355,"href":"https:\/\/radioguerrerosonline.com\/index.php\/wp-json\/wp\/v2\/posts\/8353\/revisions\/8355"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radioguerrerosonline.com\/index.php\/wp-json\/wp\/v2\/media\/8354"}],"wp:attachment":[{"href":"https:\/\/radioguerrerosonline.com\/index.php\/wp-json\/wp\/v2\/media?parent=8353"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radioguerrerosonline.com\/index.php\/wp-json\/wp\/v2\/categories?post=8353"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radioguerrerosonline.com\/index.php\/wp-json\/wp\/v2\/tags?post=8353"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}